{"id":30,"date":"2023-08-03T10:55:43","date_gmt":"2023-08-03T10:55:43","guid":{"rendered":"https:\/\/lecloudesalpilles.com\/?page_id=30"},"modified":"2023-08-09T10:47:33","modified_gmt":"2023-08-09T10:47:33","slug":"villages-en-provence","status":"publish","type":"page","link":"https:\/\/lecloudesalpilles.com\/en\/villages-in-provence-2","title":{"rendered":"To visit"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":126,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-30","page","type-page","status-publish","has-post-thumbnail","czr-hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00c0 visiter - Les villages en Provence Le Clou des Alpilles<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez nos recommandations de villages en provence \u00e0 visiter lors de votre s\u00e9jour au Clou des Alpilles\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lecloudesalpilles.com\/en\/villages-in-provence-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c0 visiter - Les villages en Provence Le Clou des Alpilles\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez nos recommandations de villages en provence \u00e0 visiter lors de votre s\u00e9jour au Clou des Alpilles\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lecloudesalpilles.com\/en\/villages-in-provence-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Clou des Alpilles\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100094620850987\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-09T10:47:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lecloudesalpilles.com\/wp-content\/uploads\/2023\/08\/Les-baux-de-provence.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"682\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"SearchResultsPage\"],\"@id\":\"https:\\\/\\\/lecloudesalpilles.com\\\/villages-en-provence\",\"url\":\"https:\\\/\\\/lecloudesalpilles.com\\\/villages-en-provence\",\"name\":\"\u00c0 visiter - Les villages en Provence Le Clou des Alpilles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lecloudesalpilles.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lecloudesalpilles.com\\\/villages-en-provence#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lecloudesalpilles.com\\\/villages-en-provence#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lecloudesalpilles.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Les-baux-de-provence.jpeg\",\"datePublished\":\"2023-08-03T10:55:43+00:00\",\"dateModified\":\"2023-08-09T10:47:33+00:00\",\"description\":\"D\u00e9couvrez nos recommandations de villages en provence \u00e0 visiter lors de votre s\u00e9jour au Clou des Alpilles\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lecloudesalpilles.com\\\/villages-en-provence#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lecloudesalpilles.com\\\/villages-en-provence\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/lecloudesalpilles.com\\\/villages-en-provence#primaryimage\",\"url\":\"https:\\\/\\\/lecloudesalpilles.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Les-baux-de-provence.jpeg\",\"contentUrl\":\"https:\\\/\\\/lecloudesalpilles.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Les-baux-de-provence.jpeg\",\"width\":1024,\"height\":682},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lecloudesalpilles.com\\\/villages-en-provence#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lecloudesalpilles.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c0 visiter\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lecloudesalpilles.com\\\/#website\",\"url\":\"https:\\\/\\\/lecloudesalpilles.com\\\/\",\"name\":\"Le Clou des Alpilles\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lecloudesalpilles.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Places to visit - Villages in Provence Le Clou des Alpilles","description":"Discover our recommendations for villages in Provence to visit during your stay at Le Clou des Alpilles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lecloudesalpilles.com\/en\/villages-in-provence-2\/","og_locale":"en_GB","og_type":"article","og_title":"\u00c0 visiter - Les villages en Provence Le Clou des Alpilles","og_description":"D\u00e9couvrez nos recommandations de villages en provence \u00e0 visiter lors de votre s\u00e9jour au Clou des Alpilles","og_url":"https:\/\/lecloudesalpilles.com\/en\/villages-in-provence-2\/","og_site_name":"Le Clou des Alpilles","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100094620850987","article_modified_time":"2023-08-09T10:47:33+00:00","og_image":[{"width":1024,"height":682,"url":"https:\/\/lecloudesalpilles.com\/wp-content\/uploads\/2023\/08\/Les-baux-de-provence.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","SearchResultsPage"],"@id":"https:\/\/lecloudesalpilles.com\/villages-en-provence","url":"https:\/\/lecloudesalpilles.com\/villages-en-provence","name":"Places to visit - Villages in Provence Le Clou des Alpilles","isPartOf":{"@id":"https:\/\/lecloudesalpilles.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lecloudesalpilles.com\/villages-en-provence#primaryimage"},"image":{"@id":"https:\/\/lecloudesalpilles.com\/villages-en-provence#primaryimage"},"thumbnailUrl":"https:\/\/lecloudesalpilles.com\/wp-content\/uploads\/2023\/08\/Les-baux-de-provence.jpeg","datePublished":"2023-08-03T10:55:43+00:00","dateModified":"2023-08-09T10:47:33+00:00","description":"Discover our recommendations for villages in Provence to visit during your stay at Le Clou des Alpilles","breadcrumb":{"@id":"https:\/\/lecloudesalpilles.com\/villages-en-provence#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lecloudesalpilles.com\/villages-en-provence"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/lecloudesalpilles.com\/villages-en-provence#primaryimage","url":"https:\/\/lecloudesalpilles.com\/wp-content\/uploads\/2023\/08\/Les-baux-de-provence.jpeg","contentUrl":"https:\/\/lecloudesalpilles.com\/wp-content\/uploads\/2023\/08\/Les-baux-de-provence.jpeg","width":1024,"height":682},{"@type":"BreadcrumbList","@id":"https:\/\/lecloudesalpilles.com\/villages-en-provence#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lecloudesalpilles.com\/"},{"@type":"ListItem","position":2,"name":"\u00c0 visiter"}]},{"@type":"WebSite","@id":"https:\/\/lecloudesalpilles.com\/#website","url":"https:\/\/lecloudesalpilles.com\/","name":"Le Clou des Alpilles","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lecloudesalpilles.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/lecloudesalpilles.com\/en\/wp-json\/wp\/v2\/pages\/30","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lecloudesalpilles.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lecloudesalpilles.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lecloudesalpilles.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lecloudesalpilles.com\/en\/wp-json\/wp\/v2\/comments?post=30"}],"version-history":[{"count":1,"href":"https:\/\/lecloudesalpilles.com\/en\/wp-json\/wp\/v2\/pages\/30\/revisions"}],"predecessor-version":[{"id":31,"href":"https:\/\/lecloudesalpilles.com\/en\/wp-json\/wp\/v2\/pages\/30\/revisions\/31"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lecloudesalpilles.com\/en\/wp-json\/wp\/v2\/media\/126"}],"wp:attachment":[{"href":"https:\/\/lecloudesalpilles.com\/en\/wp-json\/wp\/v2\/media?parent=30"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}